{"id":16,"count":2997,"description":"","link":"https:\/\/www.aascj.org.br\/home\/category\/boletim\/","name":"boletim","slug":"boletim","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivos boletim - AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aascj.org.br\/home\/category\/boletim\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos boletim - AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aascj.org.br\/home\/category\/boletim\/\" \/>\n<meta property=\"og:site_name\" content=\"AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/category\/boletim\/\",\"url\":\"https:\/\/www.aascj.org.br\/home\/category\/boletim\/\",\"name\":\"Arquivos boletim - AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus\",\"isPartOf\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/category\/boletim\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/category\/boletim\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.aascj.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"boletim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/#website\",\"url\":\"https:\/\/www.aascj.org.br\/home\/\",\"name\":\"AASCJ Associa\u00e7\u00e3o Apostolado do Sagrado Cora\u00e7\u00e3o de Jesus\",\"description\":\"AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus\",\"publisher\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.aascj.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/#organization\",\"name\":\"AASCJ\",\"url\":\"https:\/\/www.aascj.org.br\/home\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.aascj.org.br\/home\/wp-content\/uploads\/2020\/02\/logo-sem-texto.png\",\"contentUrl\":\"https:\/\/www.aascj.org.br\/home\/wp-content\/uploads\/2020\/02\/logo-sem-texto.png\",\"width\":146,\"height\":201,\"caption\":\"AASCJ\"},\"image\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sagradocoracao\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos boletim - AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aascj.org.br\/home\/category\/boletim\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos boletim - AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus","og_url":"https:\/\/www.aascj.org.br\/home\/category\/boletim\/","og_site_name":"AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.aascj.org.br\/home\/category\/boletim\/","url":"https:\/\/www.aascj.org.br\/home\/category\/boletim\/","name":"Arquivos boletim - AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus","isPartOf":{"@id":"https:\/\/www.aascj.org.br\/home\/#website"},"breadcrumb":{"@id":"https:\/\/www.aascj.org.br\/home\/category\/boletim\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aascj.org.br\/home\/category\/boletim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.aascj.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"boletim"}]},{"@type":"WebSite","@id":"https:\/\/www.aascj.org.br\/home\/#website","url":"https:\/\/www.aascj.org.br\/home\/","name":"AASCJ Associa\u00e7\u00e3o Apostolado do Sagrado Cora\u00e7\u00e3o de Jesus","description":"AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus","publisher":{"@id":"https:\/\/www.aascj.org.br\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aascj.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.aascj.org.br\/home\/#organization","name":"AASCJ","url":"https:\/\/www.aascj.org.br\/home\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.aascj.org.br\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.aascj.org.br\/home\/wp-content\/uploads\/2020\/02\/logo-sem-texto.png","contentUrl":"https:\/\/www.aascj.org.br\/home\/wp-content\/uploads\/2020\/02\/logo-sem-texto.png","width":146,"height":201,"caption":"AASCJ"},"image":{"@id":"https:\/\/www.aascj.org.br\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sagradocoracao\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/categories\/16"}],"collection":[{"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/posts?categories=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}