	<link rel='stylesheet' href='/home/wp-content/plugins/transferencia-de-conteudo/css/jquery.fancybox-1.3.4.css' type='text/css' />
	<style type="text/css">
	.fancybox-opened .fancybox-skin{
		background: #FFF;
		min-height: 475px !important;
	}
	.fancybox-inner{
		min-height: 459px !important;
	}
	iframe{
		overflow-y: hidden !important;
	}
	iframe html{
		overflow-y: hidden !important;
	}
	@media (max-width: 991px) {
		.container-fluid img {width:100% !important; height: auto !important;}
	}
	</style> 
	{"id":45792,"date":"2017-05-04T12:00:52","date_gmt":"2017-05-04T15:00:52","guid":{"rendered":"http:\/\/www.aascj.org.br\/home\/?p=45792"},"modified":"2017-05-04T12:00:52","modified_gmt":"2017-05-04T15:00:52","slug":"centenario-fatima","status":"publish","type":"post","link":"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/","title":{"rendered":"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!"},"content":{"rendered":"<p style=\"text-align: center; background-color: #890304; padding: 20px 0; color: #ffffff!important; font-size: 20px;\"><strong><span style=\"color: #890304;\">;<\/span><br \/>\nCENTEN\u00c1RIO DE NOSSA SENHORA DE F\u00c1TIMA,<\/strong><strong><br \/>\n<span style=\"color: #890304;\">.<\/span><\/strong><\/p>\n<p style=\"padding-left: 90px;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><strong><span style=\"color: #800080;\"><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #800000;\">Estamos prestes a iniciar as comemora\u00e7\u00f5es do Centen\u00e1rio das Apari\u00e7\u00f5es de Nossa Senhora em F\u00e1tima, Portugal (1917 a 2017).<\/span><\/span><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400; font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-size: 14pt;\"><strong>N<\/strong><\/span>as diversas apari\u00e7\u00f5es, a Virgem Maria fez alertas severos, deixou apelos e promessas para mim, para voc\u00ea, para a humanidade.<\/span><\/p>\n<p><span style=\"font-weight: 400; font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Mas\u2026<\/span><\/p>\n<p style=\"padding-left: 90px;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800000;\"><b>N\u00f3s atendemos seus pedidos?<\/b><\/span><\/p>\n<p style=\"padding-left: 90px;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800000;\"><b>N\u00f3s observamos seus alertas?<\/b><\/span><\/p>\n<p style=\"padding-left: 90px;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800000;\"><b>N\u00f3s somos merecedores de suas promessas?<\/b><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><b>Estas e outras quest\u00f5es ser\u00e3o respondidas e abordadas num <\/b><span style=\"font-weight: 400;\">evento sem precedentes, digno da festa que se comemora.<\/span><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-weight: 400;\">Trata-se da Confer\u00eancia, uma parceria entre o Instituto Plinio Corr\u00eaa de Oliveira, a Associa\u00e7\u00e3o Devotos de F\u00e1tima e nossa Associa\u00e7\u00e3o Apostolado Sagrado Cora\u00e7\u00e3o de Jesus:<\/span><\/span><\/p>\n<p style=\"padding-left: 90px;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><b><br \/>\n<span style=\"color: #800000;\">O que a mensagem de F\u00e1tima tem a nos dizer 100 anos depois?<\/span><\/b><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">A ser realizada no dia 11 de mar\u00e7o \u00e0s 19:30 Hrs, antev\u00e9spera da Festa de 100 anos!<\/span><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-weight: 400;\">Onde \u00e9 apenas obrigat\u00f3ria sua <\/span><b><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/conferencia.ipco.org.br\/centenario-de-fatima?utm_source=leadlovers&amp;utm_medium=email&amp;utm_campaign=Nossa%20pr%C3%B3xima%20confer%C3%AAncia%20no%20Club%20Homs\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 14pt;\">inscri\u00e7\u00e3o<\/span><\/a><\/span>, <\/b><span style=\"font-weight: 400;\">reunindo especialistas, estudiosos da Mensagem de F\u00e1tima;<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/conferencia.ipco.org.br\/centenario-de-fatima?utm_source=leadlovers&amp;utm_medium=email&amp;utm_campaign=Nossa%20pr%C3%B3xima%20confer%C3%AAncia%20no%20Club%20Homs\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 18pt; color: #0000ff;\"><b>Inscreva-se Aqui!<\/b><\/span><\/a><\/p>\n<p><span style=\"font-weight: 400; font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-45848 size-thumbnail\" src=\"http:\/\/www.aascj.org.br\/home\/wp-content\/uploads\/2017\/05\/Dr.-Borelli-150x150.png\" alt=\"Dr.-Borelli\" width=\"150\" height=\"150\" \/>Como o Dr. Borelli, fatim\u00f3logo, que se dedica ao estudo da Mensagem desde os 16 anos, autor de um dos maiores op\u00fasculos de F\u00e1tima escritos at\u00e9 hoje, com mais de 5 milh\u00f5es de exemplares distribu\u00eddos pelo mundo.<\/span><\/p>\n<p><span style=\"font-weight: 400; font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Dr. Borelli nos esclarecer\u00e1 sob uma vis\u00e3o at\u00e9 hoje pouco abordada sobre o assunto:<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400; font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Porqu\u00ea a mensagem de F\u00e1tima n\u00e3o foi revelada em 1960, como f\u00f4ra indicado por Nossa Senhora \u00e0 Irm\u00e3 L\u00facia?<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-weight: 400;\">Vale a\u00a0pena conferir, n\u00e3o deixe de se <\/span><a href=\"http:\/\/conferencia.ipco.org.br\/centenario-de-fatima?utm_source=leadlovers&amp;utm_medium=email&amp;utm_campaign=Nossa%20pr%C3%B3xima%20confer%C3%AAncia%20no%20Club%20Homs\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 14pt; color: #0000ff;\"><b>inscrever<\/b><\/span><\/a><span style=\"font-weight: 400;\">, este evento ser\u00e1 \u00fanico!<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400; font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-45849 size-thumbnail\" src=\"http:\/\/www.aascj.org.br\/home\/wp-content\/uploads\/2017\/05\/pe-Renato-Leite-150x150.png\" alt=\"pe-Renato-Leite\" width=\"150\" height=\"150\" \/>Teremos tamb\u00e9m a presen\u00e7a do Cl\u00e9rigo, Pe. Renato Leite, sacerdote do clero de Santo Amaro, tamb\u00e9m amante da Mensagem de F\u00e1tima;<\/span><\/p>\n<p><span style=\"font-weight: 400; font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Que nos far\u00e1 uma abordagem mais espiritual frente \u00e0quilo que Nossa Senhora advertiu como meios de Salva\u00e7\u00e3o, o Jejum, a Ora\u00e7\u00e3o e a Penit\u00eancia, at\u00e9 onde cumprimos?<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/conferencia.ipco.org.br\/centenario-de-fatima?utm_source=leadlovers&amp;utm_medium=email&amp;utm_campaign=Nossa%20pr%C3%B3xima%20confer%C3%AAncia%20no%20Club%20Homs\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 18pt;\"><b><br \/>\nN\u00e3o deixe de marcar sua presen\u00e7a neste dia, contamos com voc\u00ea Ap\u00f3stolo de F\u00e1tima!<\/b><\/span><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400; font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><br \/>\nEste encontro ser\u00e1 no anfiteatro do Club Homs, na regi\u00e3o da Paulista, regi\u00e3o de f\u00e1cil acesso e com estacionamento no local!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: center;\"><span style=\"color: #0000ff; font-size: 14pt;\"><a style=\"color: #0000ff;\" href=\"http:\/\/conferencia.ipco.org.br\/centenario-de-fatima?utm_source=leadlovers&amp;utm_medium=email&amp;utm_campaign=Nossa%20pr%C3%B3xima%20confer%C3%AAncia%20no%20Club%20Homs\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-family: verdana, geneva, sans-serif;\"><b>Inscreva-se e tenha mais informa\u00e7\u00f5es sobre a localiza\u00e7\u00e3o<\/b><\/span><\/a><\/span><\/h5>\n<p style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">* \u00a0* \u00a0*<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos prestes a iniciar as comemora\u00e7\u00f5es do Centen\u00e1rio das Apari\u00e7\u00f5es de Nossa Senhora em F\u00e1tima, Portugal (1917 a 2017).<\/p>\n","protected":false},"author":32,"featured_media":45883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[]},"categories":[16],"tags":[375,2268],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Centen\u00e1rio da Mensagem de F\u00e1tima, um evento especial, confira!<\/title>\n<meta name=\"description\" content=\"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centen\u00e1rio da Mensagem de F\u00e1tima, um evento especial, confira!\" \/>\n<meta property=\"og:description\" content=\"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/\" \/>\n<meta property=\"og:site_name\" content=\"AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sagradocoracao\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-04T15:00:52+00:00\" \/>\n<meta name=\"author\" content=\"Luiz Felipe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luiz Felipe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/\"},\"author\":{\"name\":\"Luiz Felipe\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/#\/schema\/person\/a9d00615efccd73824c85aebd3762c6c\"},\"headline\":\"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!\",\"datePublished\":\"2017-05-04T15:00:52+00:00\",\"dateModified\":\"2017-05-04T15:00:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/\"},\"wordCount\":390,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/#organization\"},\"keywords\":[\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\",\"Nossa Senhora de F\u00e1tima\"],\"articleSection\":[\"boletim\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/\",\"url\":\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/\",\"name\":\"Centen\u00e1rio da Mensagem de F\u00e1tima, um evento especial, confira!\",\"isPartOf\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/#website\"},\"datePublished\":\"2017-05-04T15:00:52+00:00\",\"dateModified\":\"2017-05-04T15:00:52+00:00\",\"description\":\"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.aascj.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/#website\",\"url\":\"https:\/\/www.aascj.org.br\/home\/\",\"name\":\"AASCJ Associa\u00e7\u00e3o Apostolado do Sagrado Cora\u00e7\u00e3o de Jesus\",\"description\":\"AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus\",\"publisher\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.aascj.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/#organization\",\"name\":\"AASCJ\",\"url\":\"https:\/\/www.aascj.org.br\/home\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.aascj.org.br\/home\/wp-content\/uploads\/2020\/02\/logo-sem-texto.png\",\"contentUrl\":\"https:\/\/www.aascj.org.br\/home\/wp-content\/uploads\/2020\/02\/logo-sem-texto.png\",\"width\":146,\"height\":201,\"caption\":\"AASCJ\"},\"image\":{\"@id\":\"https:\/\/www.aascj.org.br\/home\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sagradocoracao\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/#\/schema\/person\/a9d00615efccd73824c85aebd3762c6c\",\"name\":\"Luiz Felipe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.aascj.org.br\/home\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f8f0a14d57a57f103e42363994b25ba9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f8f0a14d57a57f103e42363994b25ba9?s=96&d=mm&r=g\",\"caption\":\"Luiz Felipe\"},\"url\":\"https:\/\/www.aascj.org.br\/home\/author\/luiz-merencianopmk-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centen\u00e1rio da Mensagem de F\u00e1tima, um evento especial, confira!","description":"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/","og_locale":"pt_BR","og_type":"article","og_title":"Centen\u00e1rio da Mensagem de F\u00e1tima, um evento especial, confira!","og_description":"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!","og_url":"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/","og_site_name":"AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus","article_publisher":"https:\/\/www.facebook.com\/sagradocoracao\/","article_published_time":"2017-05-04T15:00:52+00:00","author":"Luiz Felipe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luiz Felipe","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/#article","isPartOf":{"@id":"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/"},"author":{"name":"Luiz Felipe","@id":"https:\/\/www.aascj.org.br\/home\/#\/schema\/person\/a9d00615efccd73824c85aebd3762c6c"},"headline":"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!","datePublished":"2017-05-04T15:00:52+00:00","dateModified":"2017-05-04T15:00:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/"},"wordCount":390,"commentCount":0,"publisher":{"@id":"https:\/\/www.aascj.org.br\/home\/#organization"},"keywords":["Associa\u00e7\u00e3o Devotos de F\u00e1tima","Nossa Senhora de F\u00e1tima"],"articleSection":["boletim"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/","url":"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/","name":"Centen\u00e1rio da Mensagem de F\u00e1tima, um evento especial, confira!","isPartOf":{"@id":"https:\/\/www.aascj.org.br\/home\/#website"},"datePublished":"2017-05-04T15:00:52+00:00","dateModified":"2017-05-04T15:00:52+00:00","description":"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!","breadcrumb":{"@id":"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aascj.org.br\/home\/2017\/05\/centenario-fatima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.aascj.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"UM CONVITE ESPECIAL PARA VOC\u00ca! Em comemora\u00e7\u00e3o ao Centen\u00e1rio da Mensagem de F\u00e1tima, lhe preparamos um evento especial, confira!"}]},{"@type":"WebSite","@id":"https:\/\/www.aascj.org.br\/home\/#website","url":"https:\/\/www.aascj.org.br\/home\/","name":"AASCJ Associa\u00e7\u00e3o Apostolado do Sagrado Cora\u00e7\u00e3o de Jesus","description":"AASCJ Associa\u00e7\u00e3o Apostolado Sagrado cora\u00e7\u00e3o de Jesus","publisher":{"@id":"https:\/\/www.aascj.org.br\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aascj.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.aascj.org.br\/home\/#organization","name":"AASCJ","url":"https:\/\/www.aascj.org.br\/home\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.aascj.org.br\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.aascj.org.br\/home\/wp-content\/uploads\/2020\/02\/logo-sem-texto.png","contentUrl":"https:\/\/www.aascj.org.br\/home\/wp-content\/uploads\/2020\/02\/logo-sem-texto.png","width":146,"height":201,"caption":"AASCJ"},"image":{"@id":"https:\/\/www.aascj.org.br\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sagradocoracao\/"]},{"@type":"Person","@id":"https:\/\/www.aascj.org.br\/home\/#\/schema\/person\/a9d00615efccd73824c85aebd3762c6c","name":"Luiz Felipe","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.aascj.org.br\/home\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f8f0a14d57a57f103e42363994b25ba9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8f0a14d57a57f103e42363994b25ba9?s=96&d=mm&r=g","caption":"Luiz Felipe"},"url":"https:\/\/www.aascj.org.br\/home\/author\/luiz-merencianopmk-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/posts\/45792"}],"collection":[{"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/comments?post=45792"}],"version-history":[{"count":0,"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/posts\/45792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/media?parent=45792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/categories?post=45792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aascj.org.br\/home\/wp-json\/wp\/v2\/tags?post=45792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}